{"id":22758,"date":"2024-07-30T16:50:23","date_gmt":"2024-07-30T13:50:23","guid":{"rendered":"https:\/\/joldijagroup.com\/energie-solaire-composants\/"},"modified":"2026-02-02T09:34:44","modified_gmt":"2026-02-02T07:34:44","slug":"energie-solaire-composants","status":"publish","type":"page","link":"https:\/\/joldijagroup.com\/fr\/energie-solaire-composants\/","title":{"rendered":"\u00c9nergie solaire Composants"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"22758\" class=\"elementor elementor-22758 elementor-12037\">\n\t\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-5ee1fa58 elementor-section-full_width elementor-section-height-min-height alpha-section-stretched elementor-section-height-default elementor-section-items-middle\" data-id=\"5ee1fa58\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4529d987 \" data-id=\"4529d987\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f76eba3 elementor-widget elementor-widget-udesign_widget_banner\" data-id=\"5f76eba3\" data-element_type=\"widget\" data-widget_type=\"udesign_widget_banner.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"banner banner-fixed\">\t<figure class=\"banner-img\">\r\n\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1150\" height=\"500\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/2024\/08\/80-AKRILAS-20-1.png\" class=\"attachment-full size-full\" alt=\"Fittings for Solar Power\" srcset=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/2024\/08\/80-AKRILAS-20-1.png 1150w, https:\/\/joldijagroup.com\/wp-content\/uploads\/2024\/08\/80-AKRILAS-20-1-1024x445.png 1024w, https:\/\/joldijagroup.com\/wp-content\/uploads\/2024\/08\/80-AKRILAS-20-1-768x334.png 768w\" sizes=\"(max-width: 1150px) 100vw, 1150px\" \/>\t<\/figure>\r\n\t<div class=\"banner-content t-mc\"><h3 class=\"banner-item elementor-repeater-item-51d814a item-block text\">Composants de l'\u00e9nergie solaire<\/h3><p class=\"banner-item elementor-repeater-item-47d6081 item-block text\">Des composants solaires fiables pour des installations plus rapides, plus fluides et plus efficaces.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-4b35813 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"4b35813\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b903615 \" data-id=\"b903615\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e8bddd elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1e8bddd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rapide. Fiable. Construit pour un avenir durable.  <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e5b53b elementor-widget elementor-widget-text-editor\" data-id=\"1e5b53b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"\" data-start=\"272\" data-end=\"578\">En tant qu&#8217;entreprise engag\u00e9e \u00e0 soutenir le passage \u00e0 l&#8217;\u00e9nergie durable, nous prenons nos responsabilit\u00e9s au-del\u00e0 des mots &#8211; nous agissons. C&#8217;est pourquoi nous avons \u00e9largi notre portefeuille de produits afin de proposer aux professionnels de l&#8217;installation solaire une <strong data-start=\"497\" data-end=\"552\">gamme de composants de montage fiables et de haute qualit\u00e9<\/strong>, pr\u00eats \u00e0 \u00eatre livr\u00e9s rapidement. <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-db0c872 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"db0c872\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6934282 \" data-id=\"6934282\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c71ba3f elementor-widget elementor-widget-image\" data-id=\"c71ba3f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2048\" height=\"1024\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/05\/DJI_0550inj-2048x1024.jpg\" class=\"attachment-2048x2048 size-2048x2048 wp-image-18383\" alt=\"Solar Power Components\" srcset=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/05\/DJI_0550inj-2048x1024.jpg 2048w, https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/05\/DJI_0550inj-1024x512.jpg 1024w, https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/05\/DJI_0550inj-768x384.jpg 768w, https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/05\/DJI_0550inj-1536x768.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-7d57ffb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d57ffb\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ec1053 \" data-id=\"3ec1053\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9247502 elementor-widget elementor-widget-text-editor\" data-id=\"9247502\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"\" data-start=\"272\" data-end=\"578\">Notre objectif est simple : aider les installateurs \u00e0 se concentrer sur ce qu&#8217;ils font le mieux &#8211; l&#8217;installation &#8211; tandis que<strong data-start=\"600\" data-end=\"694\"> nous nous occupons du reste.<\/strong> Nous proposons actuellement deux syst\u00e8mes optimis\u00e9s pour diff\u00e9rents types de toits : <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-d3605d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3605d0\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-895be85 \" data-id=\"895be85\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ebe713 cs_8-img-box elementor-widget__width-auto elementor-invisible elementor-widget elementor-widget-udesign_widget_imagebox\" data-id=\"9ebe713\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"udesign_widget_imagebox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"image-box image-box-card image-box-gallery overlay-zoom overlay-dark\"><a href=\"#pitched\"><figure><img decoding=\"async\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/elementor\/thumbs\/Solar-components-2-1-scaled-r6306n99bvc622v4b0pq1bmq85ifjkhanisbwx3qc8.jpg\" title=\"Fitting_solutions_for_Furniture_and_Construction_Assembly_items_and_Furniture_fittings_Plasterboard_Profiles_Solar_Power_Components_Fasteners_Sustainability_Quality_Industrial_manufacturing_Pitched_Roof_Systems_joldijagroup_com\" alt=\"Pitched Roof Systems\" loading=\"lazy\" \/><\/figure><\/a><div class=\"image-box-info\"><h3 class=\"title\"><a href=\"#pitched\">Syst\u00e8mes de toits en pente<\/a><\/h3><p class=\"content\">Notre syst\u00e8me de montage pour toits en pente est compatible avec les toits en ardoise, en t\u00f4le et en tuiles, en fonction des composants s\u00e9lectionn\u00e9s.  <\/p><\/div><div class=\"image-box-action content-hover\"><a href=\"#pitched\" class=\"btn btn-ellipse   u-icon-long-arrow-right\"><\/a><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-96c3f55 \" data-id=\"96c3f55\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9086b10 cs_8-img-box elementor-widget__width-auto elementor-invisible elementor-widget elementor-widget-udesign_widget_imagebox\" data-id=\"9086b10\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"udesign_widget_imagebox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"image-box image-box-card image-box-gallery overlay-zoom overlay-dark\"><a href=\"#flat\"><figure><img decoding=\"async\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/elementor\/thumbs\/Flat-roof-scaled-r630gbzdreljpeskqpgb8dmqm3rlv9xpngtgykqo7s.jpg\" title=\"Fitting_solutions_for_Furniture_and_Construction_Assembly_items_and_Furniture_fittings_Plasterboard_Profiles_Solar_Power_Components_Fasteners_Sustainability_Quality_Industrial_manufacturing_Flat_Roof_Systems_joldijagroup_com\" alt=\"Flat Roof Systems\" loading=\"lazy\" \/><\/figure><\/a><div class=\"image-box-info\"><h3 class=\"title\"><a href=\"#flat\">Syst\u00e8mes de toits plats<\/a><\/h3><p class=\"content\">Notre syst\u00e8me de toit plat est facile et rapide \u00e0 installer et a une longue dur\u00e9e de vie. Le syst\u00e8me est test\u00e9 en soufflerie.   <\/p><\/div><div class=\"image-box-action content-hover\"><a href=\"#flat\" class=\"btn btn-ellipse   u-icon-long-arrow-right\"><\/a><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-699e929 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"699e929\" data-element_type=\"section\" id=\"pitched\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a378a20 \" data-id=\"a378a20\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d6f721 elementor-widget elementor-widget-spacer\" data-id=\"6d6f721\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-f664d5c elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"f664d5c\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-274acb0 \" data-id=\"274acb0\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7cb36e elementor-widget elementor-widget-heading\" data-id=\"a7cb36e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Syst\u00e8me de toit en pente : Montage solaire intelligent pour les toits inclin\u00e9s<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-bc17312 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc17312\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b4b845 \" data-id=\"1b4b845\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12331d6 elementor-widget elementor-widget-text-editor\" data-id=\"12331d6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"\" data-start=\"42\" data-end=\"233\">Am\u00e9liorez vos offres d&#8217;\u00e9nergie renouvelable avec nos syst\u00e8mes solaires de pointe mont\u00e9s sur toiture, con\u00e7us pour l&#8217;efficacit\u00e9, la fiabilit\u00e9 et l&#8217;installation transparente sur une large gamme de structures de toit inclin\u00e9es.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-5a593f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a593f5\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-af3b67b \" data-id=\"af3b67b\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ed86df elementor-widget elementor-widget-heading\" data-id=\"0ed86df\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Principaux avantages pour votre entreprise :<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-b804b01 elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-height-default\" data-id=\"b804b01\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f18d12b \" data-id=\"f18d12b\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e69e9d5 cs_8-img-box elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-udesign_widget_imagebox\" data-id=\"e69e9d5\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"udesign_widget_imagebox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"image-box image-box-card image-box-gallery overlay-zoom overlay-dark\"><figure><img decoding=\"async\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/elementor\/thumbs\/Solar-components-darker-f-scaled-r631sdif2kdrm631z5lk22lw2b9lotu4g38i7yor50.jpg\" title=\"Fitting_solutions_for_Furniture_and_Construction_Assembly_items_and_Furniture_fittings_Plasterboard_Profiles_Solar_Power_Components_Fasteners_Sustainability_Quality_Industrial_manufacturing_Solar_Power_Components_space_efficient_joldijagroup_com\" alt=\"Solar Power Components\" loading=\"lazy\" \/><\/figure><div class=\"image-box-info\"><h3 class=\"title\">Efficace en termes d'espace et de co\u00fbts :<\/h3><p class=\"content\">Parfaits pour les maisons et les b\u00e2timents publics o\u00f9 l'espace de la cour est limit\u00e9, nos syst\u00e8mes utilisent les chevrons existants pour fixer les panneaux et optimiser l'espace disponible sur le toit.<\/p><\/div><div class=\"image-box-action content-hover\"><a href=\"#\" class=\"btn btn-ellipse   u-icon-long-arrow-right\"><\/a><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-43a529a \" data-id=\"43a529a\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9eb011 cs_8-img-box elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-udesign_widget_imagebox\" data-id=\"f9eb011\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"udesign_widget_imagebox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"image-box image-box-card image-box-gallery overlay-zoom overlay-dark\"><figure><img decoding=\"async\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/elementor\/thumbs\/pexels-trinh-tr-n-191284110-14613939gd-rgbw18zifbg2xdwk62usnogbfwxr1qoxzy4o2gawys.jpg\" title=\"pexels-trinh-tr-n-191284110-14613939gd\" alt=\"Solar Power Components\" loading=\"lazy\" \/><\/figure><div class=\"image-box-info\"><h3 class=\"title\">Compatibilit\u00e9 polyvalente<\/h3><p class=\"content\">Notre gamme de produits comprend tous les composants essentiels pour les installations d'\u00e9nergie solaire - des profil\u00e9s et goujons fabriqu\u00e9s avec pr\u00e9cision aux crochets, vis et attaches robustes - garantissant une int\u00e9gration totale avec les diff\u00e9rents mat\u00e9riaux de toiture.<\/p><\/div><div class=\"image-box-action content-hover\"><a href=\"#\" class=\"btn btn-ellipse   u-icon-long-arrow-right\"><\/a><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-654f18c \" data-id=\"654f18c\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee6350e cs_8-img-box elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-udesign_widget_imagebox\" data-id=\"ee6350e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"udesign_widget_imagebox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"image-box image-box-card image-box-gallery overlay-zoom overlay-dark\"><figure><img decoding=\"async\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/elementor\/thumbs\/pexels-cristian-rojas-8853502tu-1-r62qwzhpc0llbellez3ytu6bggdily1pyw42e70604.jpg\" title=\"Fitting_solutions_for_Furniture_and_Construction_Assembly_items_and_Furniture_fittings_Plasterboard_Profiles_Solar_Power_Components_Fasteners_Sustainability_Quality_Industrial_manufacturing_Solar_Power_Components_Trapezoidal_Profiles_joldijagroup_com\" alt=\"Solar Power Components\" loading=\"lazy\" \/><\/figure><div class=\"image-box-info\"><h3 class=\"title\">Options de composants optimis\u00e9es :<\/h3><p class=\"content\">Nous proposons deux types de profil\u00e9s pour composants d'\u00e9nergie solaire : Rails standard de 6,6 m\u00e8tres - offrant des performances et une fiabilit\u00e9 \u00e9prouv\u00e9es.\nProfils trap\u00e9zo\u00efdaux : Con\u00e7us pour une grande compatibilit\u00e9 avec la plupart des toits en t\u00f4le trap\u00e9zo\u00efdale.<\/p><\/div><div class=\"image-box-action content-hover\"><a href=\"#\" class=\"btn btn-ellipse   u-icon-long-arrow-right\"><\/a><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-fca777d \" data-id=\"fca777d\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7c34b7 cs_8-img-box elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-udesign_widget_imagebox\" data-id=\"a7c34b7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"udesign_widget_imagebox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"image-box image-box-card image-box-gallery overlay-zoom overlay-dark\"><figure><img decoding=\"async\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/elementor\/thumbs\/pexels-carolin-wenske-762365559-28286652uyj-scaled-r62q7akij1ffz3x3fvb2obkqxb0c7s1ufq6a5x3k2s.jpg\" title=\"Fitting_solutions_for_Furniture_and_Construction_Assembly_items_and_Furniture_fittings_Plasterboard_Profiles_Solar_Power_Components_Fasteners_Sustainability_Quality_Industrial_manufacturing_Solar_Power_Components_Short_rail_system_joldijagroup_com\" alt=\"Solar Power Components\" loading=\"lazy\" \/><\/figure><div class=\"image-box-info\"><h3 class=\"title\">Installation flexible :<\/h3><p class=\"content\">Notre syst\u00e8me de rails courts permet un montage vertical et horizontal des modules, avec un serrage r\u00e9glable sur les c\u00f4t\u00e9s longs ou courts du cadre, ce qui garantit une grande adaptabilit\u00e9 aux diverses exigences du projet.<\/p><\/div><div class=\"image-box-action content-hover\"><a href=\"#\" class=\"btn btn-ellipse   u-icon-long-arrow-right\"><\/a><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-cbb5387 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cbb5387\" data-element_type=\"section\" id=\"flat\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c9061a \" data-id=\"7c9061a\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8af16e7 elementor-widget elementor-widget-spacer\" data-id=\"8af16e7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-e879cc1 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"e879cc1\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5869d5 \" data-id=\"b5869d5\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da134c2 elementor-widget elementor-widget-heading\" data-id=\"da134c2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Syst\u00e8me de montage sur toit plat<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-a45397c elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"a45397c\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4619c00 \" data-id=\"4619c00\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3f0c89 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"f3f0c89\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Lorsque la rapidit\u00e9, la solidit\u00e9 et la pr\u00e9cision sont importantes, notre syst\u00e8me de toiture plate est \u00e0 la hauteur. D\u00e9velopp\u00e9 pour des installations efficaces et une durabilit\u00e9 \u00e0 long terme, il r\u00e9duit les besoins en ballast sans compromettre la stabilit\u00e9. <strong data-start=\"722\" data-end=\"824\">Rapide \u00e0 installer, <\/strong>l\u00e9ger de par sa conception, il a \u00e9t\u00e9 test\u00e9 en soufflerie pour une fiabilit\u00e9 \u00e0 toute \u00e9preuve. <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-cb07c4a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb07c4a\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-005733a \" data-id=\"005733a\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aee148c elementor-widget elementor-widget-heading\" data-id=\"aee148c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Principaux avantages pour votre entreprise :<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-24def14 elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-height-default\" data-id=\"24def14\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-9cb1298 \" data-id=\"9cb1298\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3930290 cs_8-img-box elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-udesign_widget_imagebox\" data-id=\"3930290\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"udesign_widget_imagebox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"image-box image-box-card image-box-gallery overlay-zoom overlay-dark\"><figure><img decoding=\"async\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/elementor\/thumbs\/pexels-cristian-rojas-8853537werfthg-scaled-r62pp8475op0sy5wy258qvpruo2c98blaaqa2fvzok.jpg\" title=\"Fitting_solutions_for_Furniture_and_Construction_Assembly_items_and_Furniture_fittings_Plasterboard_Profiles_Solar_Power_Components_Fasteners_Sustainability_Quality_Industrial_manufacturing_Solar_Power_components_precision_engineered_profiles_joldijagroup_com\" alt=\"Solar Power components\" loading=\"lazy\" \/><\/figure><div class=\"image-box-info\"><h3 class=\"title\">Installation rapide et facile<\/h3><p class=\"content\">La conception optimis\u00e9e garantit une installation rapide et simple sur les toits plats - gagnez du temps sur chaque projet.<\/p><\/div><div class=\"image-box-action content-hover\"><a href=\"#\" class=\"btn btn-ellipse   u-icon-long-arrow-right\"><\/a><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-58d23bf \" data-id=\"58d23bf\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-010ba6c cs_8-img-box elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-udesign_widget_imagebox\" data-id=\"010ba6c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"udesign_widget_imagebox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"image-box image-box-card image-box-gallery overlay-zoom overlay-dark\"><figure><img decoding=\"async\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/elementor\/thumbs\/DJI_0073-1-r6321q0n196f2ki9e71zupowq9708gy12csc10tt9g.jpg\" title=\"Fitting_solutions_for_Furniture_and_Construction_Assembly_items_and_Furniture_fittings_Plasterboard_Profiles_Solar_Power_Components_Fasteners_Sustainability_Quality_Industrial_manufacturing_Solar_Power_components_Aerodynamic_Structure_joldijagroup_com\" alt=\"Solar Power components\" loading=\"lazy\" \/><\/figure><div class=\"image-box-info\"><h3 class=\"title\">Structure a\u00e9rodynamique = moins de lest<\/h3><p class=\"content\">Une ing\u00e9nierie intelligente permet de r\u00e9duire le poids n\u00e9cessaire \u00e0 la fixation du syst\u00e8me, ce qui minimise les contraintes sur le toit.<\/p><\/div><div class=\"image-box-action content-hover\"><a href=\"#\" class=\"btn btn-ellipse   u-icon-long-arrow-right\"><\/a><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-91ad5d9 \" data-id=\"91ad5d9\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-575a398 cs_8-img-box elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-udesign_widget_imagebox\" data-id=\"575a398\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"udesign_widget_imagebox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"image-box image-box-card image-box-gallery overlay-zoom overlay-dark\"><figure><img decoding=\"async\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/elementor\/thumbs\/pexels-cristian-rojas-8853499gr-r62qjst7gojsgbr3erxdcnyjgvd5msp9tmnv1gjzac.jpg\" title=\"Fitting_solutions_for_Furniture_and_Construction_Assembly_items_and_Furniture_fittings_Plasterboard_Profiles_Solar_Power_Components_Fasteners_Sustainability_Quality_Industrial_manufacturing_Solar_Power_components_Wind_Tunnel_Tested_joldijagroup_com\" alt=\"Solar Power components\" loading=\"lazy\" \/><\/figure><div class=\"image-box-info\"><h3 class=\"title\">Test\u00e9 en soufflerie<\/h3><p class=\"content\">Test\u00e9 en soufflerie pour garantir la stabilit\u00e9 et la s\u00e9curit\u00e9 \u00e0 long terme dans tous les climats.<\/p><\/div><div class=\"image-box-action content-hover\"><a href=\"#\" class=\"btn btn-ellipse   u-icon-long-arrow-right\"><\/a><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b96ebaf \" data-id=\"b96ebaf\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d0d850 cs_8-img-box elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-udesign_widget_imagebox\" data-id=\"6d0d850\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"udesign_widget_imagebox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"image-box image-box-card image-box-gallery overlay-zoom overlay-dark\"><figure><img decoding=\"async\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/elementor\/thumbs\/DJI_0576re-r5u723254exzdv4qrtw702i9dkkzymp6jmiv5lqd0k.jpg\" title=\"Fitting_solutions_for_Furniture_and_Construction_Assembly_items_and_Furniture_fittings_Plasterboard_Profiles_Solar_Power_Components_Fasteners_Sustainability_Quality_Industrial_manufacturing_Solar_Power_Components_Reliable_profiles_joldijagroup_com\" alt=\"Solar Power Components\" loading=\"lazy\" \/><\/figure><div class=\"image-box-info\"><h3 class=\"title\">Long\u00e9vit\u00e9 et fiabilit\u00e9<\/h3><p class=\"content\">Construit pour r\u00e9sister aux \u00e9l\u00e9ments - une solution durable qui fonctionne pendant des ann\u00e9es.<\/p><\/div><div class=\"image-box-action content-hover\"><a href=\"#\" class=\"btn btn-ellipse   u-icon-long-arrow-right\"><\/a><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-0f28aae elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"0f28aae\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1649f1a \" data-id=\"1649f1a\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59bc908 elementor-widget elementor-widget-heading\" data-id=\"59bc908\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Composants sur mesure - Solutions personnalis\u00e9es pour une installation plus rapide et plus facile<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-ad9f29a elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"ad9f29a\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-648128c \" data-id=\"648128c\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44747b1 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"44747b1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous savons que chaque projet est unique. C&#8217;est pourquoi nous concevons et fabriquons des composants sur mesure, adapt\u00e9s pr\u00e9cis\u00e9ment \u00e0 vos besoins. Nos solutions sur mesure contribuent \u00e0 rationaliser votre processus d&#8217;assemblage, \u00e0 r\u00e9duire le temps d&#8217;installation et \u00e0 garantir des r\u00e9sultats de qualit\u00e9 sup\u00e9rieure.  <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-57247ac5 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"57247ac5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b3c716c \" data-id=\"1b3c716c\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1afd186 elementor-widget elementor-widget-heading\" data-id=\"1afd186\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vous avez besoin d'une solution adapt\u00e9e \u00e0 votre projet ? Notre \u00e9quipe est l\u00e0 pour vous aider - contactez-nous d\u00e8s aujourd'hui. <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c5f0ba9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1c5f0ba9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/joldijagroup.com\/fr\/contactez-nous\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Composants de l&#8217;\u00e9nergie solaire Des composants solaires fiables pour des installations plus rapides, plus fluides et plus efficaces. Rapide. Fiable. Construit pour un avenir durable. En tant qu&#8217;entreprise engag\u00e9e \u00e0 soutenir le passage \u00e0 l&#8217;\u00e9nergie durable, nous prenons nos responsabilit\u00e9s au-del\u00e0 des mots &#8211; nous agissons. C&#8217;est pourquoi nous avons \u00e9largi notre portefeuille de produits [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-22758","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/pages\/22758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/comments?post=22758"}],"version-history":[{"count":1,"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/pages\/22758\/revisions"}],"predecessor-version":[{"id":22827,"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/pages\/22758\/revisions\/22827"}],"wp:attachment":[{"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/media?parent=22758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}