{"id":22744,"date":"2024-08-12T15:49:43","date_gmt":"2024-08-12T12:49:43","guid":{"rendered":"https:\/\/joldijagroup.com\/qualite\/"},"modified":"2026-02-02T09:34:06","modified_gmt":"2026-02-02T07:34:06","slug":"qualite","status":"publish","type":"page","link":"https:\/\/joldijagroup.com\/fr\/qualite\/","title":{"rendered":"Qualit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"22744\" class=\"elementor elementor-22744 elementor-12481\">\n\t\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-5327904b elementor-section-full_width elementor-section-height-min-height alpha-section-stretched elementor-section-height-default elementor-section-items-middle\" data-id=\"5327904b\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d893df1 \" data-id=\"7d893df1\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5aa20 elementor-invisible elementor-widget elementor-widget-udesign_widget_banner\" data-id=\"a5aa20\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"udesign_widget_banner.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"banner banner-fixed\">\t<figure class=\"banner-img\">\r\n\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/05\/Furniture_fittings_and_assembly_items_gkp_profiles_screws_bolts_fasteners_quality_control_JOLDIJAGROUP_j2-scaled.jpg\" class=\"attachment-full size-full\" alt=\"Quality and Growth Jodijagroup\" srcset=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/05\/Furniture_fittings_and_assembly_items_gkp_profiles_screws_bolts_fasteners_quality_control_JOLDIJAGROUP_j2-scaled.jpg 2560w, https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/05\/Furniture_fittings_and_assembly_items_gkp_profiles_screws_bolts_fasteners_quality_control_JOLDIJAGROUP_j2-1024x683.jpg 1024w, https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/05\/Furniture_fittings_and_assembly_items_gkp_profiles_screws_bolts_fasteners_quality_control_JOLDIJAGROUP_j2-768x512.jpg 768w, https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/05\/Furniture_fittings_and_assembly_items_gkp_profiles_screws_bolts_fasteners_quality_control_JOLDIJAGROUP_j2-1536x1024.jpg 1536w, https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/05\/Furniture_fittings_and_assembly_items_gkp_profiles_screws_bolts_fasteners_quality_control_JOLDIJAGROUP_j2-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/figure>\r\n\t<div class=\"banner-content t-mc\"><div class=\"banner-item elementor-repeater-item-51d814a item-block\"  data-floating={\"type\":\"skr_fade_in\",\"m_track_dir\":\"\",\"m_track_speed\":0.5,\"scroll_size\":\"50\",\"scroll_stop\":\"center\"}><div class=\"floating-wrapper layer-wrapper elementor-repeater-item-51d814a-wrapper\" data-plugin='skrollr' data-options='{\"data-bottom-top\":\"transform: translate(0, 0); opacity: 0;\",\"data-center\":\"transform: translate(0%, 0%); opacity: 1;\"}' ><h3 class=\"text\">Qualit\u00e9<\/h3><\/div><\/div><p class=\"banner-item elementor-repeater-item-47d6081 item-block text\">Notre engagement en faveur de la qualit\u00e9 garantit des solutions durables, fiables et bien con\u00e7ues.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-f5cc7c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5cc7c0\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0f2481 \" data-id=\"f0f2481\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca626c4 elementor-widget elementor-widget-spacer\" data-id=\"ca626c4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-18a092ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18a092ce\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-86f6c36 \" data-id=\"86f6c36\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b9b54eb elementor-widget elementor-widget-heading\" data-id=\"5b9b54eb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contr\u00f4le de la qualit\u00e9 : Du concept \u00e0 l'am\u00e9lioration continue<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5905723 elementor-widget elementor-widget-text-editor\" data-id=\"5905723\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Le contr\u00f4le de la qualit\u00e9 au sein du groupe Joldija est un processus complet, en plusieurs \u00e9tapes, int\u00e9gr\u00e9 \u00e0 chaque phase du d\u00e9veloppement et de la fabrication des produits. Depuis les premi\u00e8res \u00e9tudes de conception jusqu&#8217;aux inspections finales avant exp\u00e9dition, nous veillons \u00e0 ce que chaque d\u00e9tail r\u00e9ponde \u00e0 des normes de qualit\u00e9 rigoureuses. Nos \u00e9quipes d\u00e9di\u00e9es \u00e0 la qualit\u00e9 en Lituanie et en Chine travaillent en \u00e9troite collaboration avec les fournisseurs afin de maintenir l&#8217;excellence des produits, d&#8217;apporter des am\u00e9liorations continues et de garantir une conformit\u00e9 totale avec les r\u00e9glementations internationales et les exigences des clients.  <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-467b063 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"467b063\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:100}\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d068d81 \" data-id=\"d068d81\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e1e19b elementor-widget elementor-widget-heading\" data-id=\"4e1e19b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c9tapes du contr\u00f4le de la qualit\u00e9  <br><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e09b96 e-transform elementor-widget-laptop__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2e09b96\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Contr\u00f4le de qualit\u00e9 int\u00e9gr\u00e9 tout au long du cycle de vie du produit.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b78a89 \" data-id=\"2b78a89\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-764618e elementor-icon-list--layout-traditional elementor-widget elementor-widget-udesign_widget_iconlist\" data-id=\"764618e\" data-element_type=\"widget\" data-widget_type=\"udesign_widget_iconlist.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-8335600\">\r\n\t\t\t<a href=\"#cross\">\t\t\t<span class=\"elementor-icon-list-text\">01  Cross-Functional Planning Meeting<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-c5fc077\">\r\n\t\t\t<a href=\"#documentation\">\t\t\t<span class=\"elementor-icon-list-text\">02  Documentation & Drawing Review<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-4c94246\">\r\n\t\t\t<a href=\"#supplier\">\t\t\t<span class=\"elementor-icon-list-text\">03 Supplier Qualification & Audits<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-507432d\">\r\n\t\t\t<a href=\"#sample\">\t\t\t<span class=\"elementor-icon-list-text\">04 Sample Approval<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-ca1d9ca\">\r\n\t\t\t<a href=\"#in\">\t\t\t<span class=\"elementor-icon-list-text\">05 In-Process Production Audits<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-1ac3b68\">\r\n\t\t\t<a href=\"#final\">\t\t\t<span class=\"elementor-icon-list-text\">06 Final Inspection & Shipment Release<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-637fa85\">\r\n\t\t\t<a href=\"#batch\">\t\t\t<span class=\"elementor-icon-list-text\">07 Batch Tests in External and Internal Laboratories<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-a244629\">\r\n\t\t\t<a href=\"#incoming\">\t\t\t<span class=\"elementor-icon-list-text\">08 Incoming Inspection & Continuous Improvement<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t<\/ul>\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-13aa281 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"13aa281\" data-element_type=\"section\" id=\"cross\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30c6ee5 \" data-id=\"30c6ee5\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-652737c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"652737c\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7874e5 \" data-id=\"f7874e5\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9903d01 elementor-widget elementor-widget-heading\" data-id=\"9903d01\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">01 R\u00e9union de planification interfonctionnelle<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3c7ff9 elementor-widget elementor-widget-text-editor\" data-id=\"a3c7ff9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Chez Joldija, l&#8217;assurance qualit\u00e9 des produits commence tr\u00e8s t\u00f4t par des r\u00e9unions de planification interfonctionnelles. Ces r\u00e9unions rassemblent diverses comp\u00e9tences &#8211; des commerciaux, qui comprennent les besoins des clients, aux chefs de produit, aux technologues et aux concepteurs, qui poss\u00e8dent un savoir-faire technique. Cette \u00e9tape proactive, align\u00e9e sur les normes ISO de d\u00e9veloppement de projet, permet d&#8217;identifier et de pr\u00e9venir les probl\u00e8mes potentiels en examinant en amont les facteurs critiques, les sc\u00e9narios d&#8217;utilisation, les \u00e9chantillons, les dessins et toutes les informations pertinentes.  <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-667f90d elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"667f90d\" data-element_type=\"section\" id=\"documentation\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;arrow&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\r\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff8d010 \" data-id=\"ff8d010\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-202c5c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"202c5c9\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-623b828 \" data-id=\"623b828\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-172fa2a elementor-widget elementor-widget-heading\" data-id=\"172fa2a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">02 Documentation et examen des dessins<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25d61aa elementor-widget elementor-widget-text-editor\" data-id=\"25d61aa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"\" data-start=\"104\" data-end=\"295\">Nous cr\u00e9ons des dessins d\u00e9taill\u00e9s en 2D et des descriptions de produits claires qui d\u00e9crivent les sp\u00e9cifications essentielles : mat\u00e9riaux, couleurs, rev\u00eatements et emballages. Avant que la production ne commence, les nouveaux fournisseurs sont soumis \u00e0 une auto-\u00e9valuation approfondie et nous visitons personnellement leurs usines pour nous assurer qu&#8217;ils sont en mesure de respecter la qualit\u00e9 et les d\u00e9lais. Les \u00e9chantillons sont soigneusement \u00e9labor\u00e9s et rigoureusement test\u00e9s par rapport \u00e0 nos normes. Une fois approuv\u00e9s, ces &#8220;\u00e9chantillons d&#8217;or&#8221; deviennent la r\u00e9f\u00e9rence pour toute la production future, garantissant une qualit\u00e9 constante \u00e0 chaque fois.   <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-65a7c2d elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"65a7c2d\" data-element_type=\"section\" id=\"supplier\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;arrow&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\r\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e322f54 \" data-id=\"e322f54\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-86a7933 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86a7933\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2539808 \" data-id=\"2539808\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-119acd6 elementor-widget elementor-widget-heading\" data-id=\"119acd6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">03 Qualification des fournisseurs et audits<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad79633 elementor-widget elementor-widget-text-editor\" data-id=\"ad79633\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"\" data-start=\"133\" data-end=\"421\">Avant d&#8217;entrer en production, les nouveaux fournisseurs proc\u00e8dent \u00e0 une auto-\u00e9valuation d\u00e9taill\u00e9e portant sur la taille de l&#8217;entreprise, sa capacit\u00e9, sa technologie, etc. Nous effectuons \u00e9galement des visites d&#8217;usine r\u00e9guli\u00e8res afin de v\u00e9rifier leur capacit\u00e9 \u00e0 respecter nos normes de qualit\u00e9 et nos d\u00e9lais de livraison. <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-9271e76 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"9271e76\" data-element_type=\"section\" id=\"sample\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;arrow&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\r\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-93de39a \" data-id=\"93de39a\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-bf4315a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf4315a\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4998188 \" data-id=\"4998188\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-264391a elementor-widget elementor-widget-heading\" data-id=\"264391a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">04 Approbation des \u00e9chantillons<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1220b6f elementor-widget elementor-widget-text-editor\" data-id=\"1220b6f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"\" data-start=\"133\" data-end=\"421\">Apr\u00e8s la production d&#8217;\u00e9chantillons, les fournisseurs envoient des \u00e9chantillons pour v\u00e9rification. Nous v\u00e9rifions la conformit\u00e9 avec les \u00e9chantillons approuv\u00e9s, les normes du client, les dessins techniques, la fonctionnalit\u00e9 et les param\u00e8tres de couleur. Les \u00e9chantillons approuv\u00e9s deviennent des r\u00e9f\u00e9rences officielles, confirm\u00e9es avec le client et archiv\u00e9es en toute s\u00e9curit\u00e9 pour r\u00e9f\u00e9rence future.  <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-b7edf43 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"b7edf43\" data-element_type=\"section\" id=\"in\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;arrow&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\r\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dcbb771 \" data-id=\"dcbb771\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-332fc2f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"332fc2f\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d727bf1 \" data-id=\"d727bf1\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6258450 elementor-widget elementor-widget-heading\" data-id=\"6258450\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">05 Audits de production en cours<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ffaa7f elementor-widget elementor-widget-text-editor\" data-id=\"4ffaa7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"\" data-start=\"127\" data-end=\"482\">Pour garantir une qualit\u00e9 constante des produits, Joldija effectue des audits de production en cours de fabrication. En Chine, nos inspecteurs de qualit\u00e9 locaux se rendent chez les fournisseurs pour passer en revue les principales \u00e9tapes de la production et \u00e9valuer la qualit\u00e9 des produits semi-finis. En Europe, ce sont nos chefs de produit qui s&#8217;en chargent.  <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-3429bda elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3429bda\" data-element_type=\"section\" id=\"final\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;arrow&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\r\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c67dbb \" data-id=\"7c67dbb\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-2400581 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2400581\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e2e326 \" data-id=\"7e2e326\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f64b04 elementor-widget elementor-widget-heading\" data-id=\"7f64b04\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">06 Inspection finale et lib\u00e9ration de l'exp\u00e9dition<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfb22b9 elementor-widget elementor-widget-text-editor\" data-id=\"cfb22b9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"\" data-start=\"133\" data-end=\"421\">Avant toute exp\u00e9dition \u00e0 l&#8217;\u00e9tranger &#8211; qu&#8217;il s&#8217;agisse d&#8217;un nouveau produit ou d&#8217;une commande r\u00e9p\u00e9titive &#8211; notre \u00e9quipe effectue une <strong data-start=\"578\" data-end=\"598\">inspection finale<\/strong> pour v\u00e9rifier les dimensions, les tol\u00e9rances et la conformit\u00e9 totale avec la documentation du produit (PD). Les rapports d&#8217;inspection sont t\u00e9l\u00e9charg\u00e9s dans notre syst\u00e8me interne et examin\u00e9s par notre \u00e9quipe qualit\u00e9 en Lituanie. Seuls les produits approuv\u00e9s sont exp\u00e9di\u00e9s &#8211; les d\u00e9fauts de conformit\u00e9 sont corrig\u00e9s et rev\u00e9rifi\u00e9s afin de garantir que chaque commande r\u00e9pond \u00e0 nos normes.  <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-6b641ed elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"6b641ed\" data-element_type=\"section\" id=\"batch\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;arrow&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\r\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-195b535 \" data-id=\"195b535\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-b4fc61d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4fc61d\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-756d412 \" data-id=\"756d412\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3efcc3f elementor-widget elementor-widget-heading\" data-id=\"3efcc3f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">07 Tests de lots dans des laboratoires externes et internes<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66f3ac5 elementor-widget elementor-widget-text-editor\" data-id=\"66f3ac5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p data-start=\"202\" data-end=\"452\">Notre entreprise accorde la plus haute priorit\u00e9 \u00e0 la qualit\u00e9 des produits. Tous les produits sont soumis \u00e0 des <strong data-start=\"335\" data-end=\"352\">tests par lots<\/strong>, effectu\u00e9s \u00e0 la fois dans nos <strong data-start=\"376\" data-end=\"401\">laboratoires internes<\/strong> et dans des<strong data-start=\"409\" data-end=\"449\"> installations d&#8217;essai externes<\/strong>. Ce processus permet de s&#8217;assurer que chaque composant r\u00e9pond aux normes les plus strictes et aux attentes des clients. Les tests internes nous permettent de contr\u00f4ler rapidement le processus de production et de rem\u00e9dier \u00e0 tout \u00e9cart, tandis que les tests externes fournissent une v\u00e9rification ind\u00e9pendante de la s\u00e9curit\u00e9, de la durabilit\u00e9 et de la long\u00e9vit\u00e9 de nos produits.   <\/p>\n<p data-start=\"766\" data-end=\"943\">Gr\u00e2ce \u00e0 ce <strong data-start=\"779\" data-end=\"821\">syst\u00e8me complet d&#8217;assurance qualit\u00e9<\/strong>, nos fournisseurs et nos clients peuvent se fier \u00e0 la fiabilit\u00e9 et \u00e0 l&#8217;excellence de nos produits tout au long de la cha\u00eene d&#8217;approvisionnement.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-dc68077 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"dc68077\" data-element_type=\"section\" id=\"incoming\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;arrow&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\r\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca31e81 \" data-id=\"ca31e81\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-2eba969 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2eba969\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c7c3fb9 \" data-id=\"c7c3fb9\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b2f8ba elementor-widget elementor-widget-heading\" data-id=\"1b2f8ba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">08 Inspection \u00e0 l'arriv\u00e9e et am\u00e9lioration continue<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8bfc80 elementor-widget elementor-widget-text-editor\" data-id=\"d8bfc80\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"\" data-start=\"194\" data-end=\"678\">Toutes les marchandises qui arrivent \u00e0 l&#8217;entrep\u00f4t de Joldija font l&#8217;objet d&#8217;une inspection initiale d\u00e9taill\u00e9e. Nous v\u00e9rifions la conformit\u00e9 avec les dessins techniques et la documentation produit (PD) et comparons les niveaux de stock pour les articles r\u00e9p\u00e9titifs. Les r\u00e9sultats des inspections sont document\u00e9s, partag\u00e9s avec les fournisseurs et utilis\u00e9s pour am\u00e9liorer continuellement la qualit\u00e9. \u00c0 la fin de chaque ann\u00e9e, nous analysons les rapports d&#8217;inspection \u00e0 l&#8217;arriv\u00e9e et \u00e0 l&#8217;\u00e9tranger (en Chine, par exemple) afin de rep\u00e9rer les tendances et les probl\u00e8mes r\u00e9currents.   <\/p>\n<p class=\"\" data-start=\"680\" data-end=\"892\">Toute non-conformit\u00e9 est enregistr\u00e9e directement dans le DP du produit, de sorte que la prochaine fois, notre \u00e9quipe et le fournisseur savent ce \u00e0 quoi il faut pr\u00eater attention. Cela permet de cibler les inspections et de fixer des priorit\u00e9s claires en mati\u00e8re d&#8217;am\u00e9lioration. <\/p>\n<p class=\"\" data-start=\"894\" data-end=\"1163\">Le processus est enti\u00e8rement num\u00e9ris\u00e9 : des boucles de retour d&#8217;information avec les inspecteurs chinois au t\u00e9l\u00e9chargement automatique des protocoles d&#8217;inspection (y compris les photos captur\u00e9es directement par scanner). Les membres de l&#8217;\u00e9quipe concern\u00e9s re\u00e7oivent des alertes en temps r\u00e9el concernant les mises \u00e0 jour, les approbations ou les changements requis. <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-e792097 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e792097\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d326b7 \" data-id=\"7d326b7\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-726170f elementor-widget elementor-widget-image\" data-id=\"726170f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/elementor\/thumbs\/Furniture_fittings_and_assembly_items_gkp_profiles_screws_bolts_fasteners_quality_control_JOLDIJAGROUP_j1-scaled-r68fdsoq27m5kdi9f58sv1dulgrsjcevh550gyz3bc.jpg\" title=\"Furniture_fittings_and_assembly_items_gkp_profiles_screws_bolts_fasteners_quality_control_JOLDIJAGROUP_j1\" alt=\"Fitting solutions for Furniture and Construction | Assembly items and Furniture fittings | Plasterboard Profiles | Solar Power Components | gkp profiles | Zig Zag spring | Table extensions | Screws | Bolts | Fasteners | Sustainability | Quality Control | Industrial manufacturing | joldijagroup.com\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-13e96b2a elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"13e96b2a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:100}\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6a33a39e \" data-id=\"6a33a39e\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bbeb116 elementor-widget elementor-widget-heading\" data-id=\"7bbeb116\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contr\u00f4le de la qualit\u00e9 de la production<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a6d2566 e-transform elementor-widget-laptop__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4a6d2566\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>  Un processus qui garantit que les produits fabriqu\u00e9s r\u00e9pondent aux exigences et aux sp\u00e9cifications \u00e9tablies. Il se compose de trois processus principaux : <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-45b2d06a \" data-id=\"45b2d06a\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3443cab0 elementor-icon-list--layout-traditional elementor-widget elementor-widget-udesign_widget_iconlist\" data-id=\"3443cab0\" data-element_type=\"widget\" data-widget_type=\"udesign_widget_iconlist.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<ul class=\"elementor-icon-list-items\">\r\n\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-8335600\">\r\n\t\t\t<a href=\"#IQC\">\t\t\t<span class=\"elementor-icon-list-text\">01  Incoming Quality Control<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-c5fc077\">\r\n\t\t\t<a href=\"#IPQC\">\t\t\t<span class=\"elementor-icon-list-text\">02  In-Process Quality Control<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-4c94246\">\r\n\t\t\t<a href=\"#FQC\">\t\t\t<span class=\"elementor-icon-list-text\">03 Final Quality Control<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/li>\r\n\t\t<\/ul>\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-a6ead48 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"a6ead48\" data-element_type=\"section\" id=\"IQC\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c549c85 \" data-id=\"c549c85\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-10bcbc5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10bcbc5\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2bec66b \" data-id=\"2bec66b\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f26cd39 elementor-widget elementor-widget-heading\" data-id=\"f26cd39\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">01 Contr\u00f4le de la qualit\u00e9 \u00e0 l'arriv\u00e9e<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4783793 elementor-widget elementor-widget-text-editor\" data-id=\"4783793\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"\" data-start=\"115\" data-end=\"514\">Nous v\u00e9rifions si les mat\u00e9riaux et les composants sont conformes aux sp\u00e9cifications et aux dessins requis, ainsi qu&#8217;aux \u00e9chantillons de r\u00e9f\u00e9rence approuv\u00e9s par le client. Les protocoles de contr\u00f4le de la qualit\u00e9 \u00e0 l&#8217;entr\u00e9e sont g\u00e9r\u00e9s num\u00e9riquement et comprennent une documentation visuelle. Ces protocoles sont accessibles aux services d&#8217;achat et de vente, ce qui permet une communication fluide avec les fournisseurs ou les clients.  <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-273d9d1 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"273d9d1\" data-element_type=\"section\" id=\"IPQC\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;arrow&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\r\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68014bb \" data-id=\"68014bb\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-4e506cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e506cf\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9adffc \" data-id=\"b9adffc\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7df9451 elementor-widget elementor-widget-heading\" data-id=\"7df9451\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">02 Contr\u00f4le de la qualit\u00e9 en cours de fabrication<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-a9d665a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9d665a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8f73220 \" data-id=\"8f73220\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87a3894 elementor-widget elementor-widget-udesign_widget_flipbox\" data-id=\"87a3894\" data-element_type=\"widget\" data-widget_type=\"udesign_widget_flipbox.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<div id=\"flipbox-87a3894\" class=\"flipbox slide fb-slide-left\" data-flipbox-settings=\"{\r\n\t'effect': fb-slide-left}\">\r\n\t<!-- Front Side Content -->\r\n\t<div id=\"flipbox_front-87a3894\" class=\"flipbox_front center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\t\t\t<h3 class=\"flipbox-title\">\r\n\t\t\t\tContr\u00f4le continu de la production\t\t\t<\/h3>\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<!-- Back Side Content -->\r\n\t<div id=\"flipbox_back-87a3894\" class=\"flipbox_back center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\t\t\t<p class=\"flipbox-description\">\r\n\t\t\t\tTous les processus de production sont constamment supervis\u00e9s et inspect\u00e9s afin de garantir une qualit\u00e9 et une conformit\u00e9 \u00e9lev\u00e9es \u00e0 chaque \u00e9tape, des mati\u00e8res premi\u00e8res au produit fini.\t\t\t<\/p>\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-80e7d31 \" data-id=\"80e7d31\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-140ab62 elementor-widget elementor-widget-udesign_widget_flipbox\" data-id=\"140ab62\" data-element_type=\"widget\" data-widget_type=\"udesign_widget_flipbox.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<div id=\"flipbox-140ab62\" class=\"flipbox slide fb-slide-left\" data-flipbox-settings=\"{\r\n\t'effect': fb-slide-left}\">\r\n\t<!-- Front Side Content -->\r\n\t<div id=\"flipbox_front-140ab62\" class=\"flipbox_front center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\t\t\t<h3 class=\"flipbox-title\">\r\n\t\t\t\tAssemblage et v\u00e9rification des produits\t\t\t<\/h3>\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<!-- Back Side Content -->\r\n\t<div id=\"flipbox_back-140ab62\" class=\"flipbox_back center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\t\t\t<p class=\"flipbox-description\">\r\n\t\t\t\tDes contr\u00f4les minutieux sont effectu\u00e9s pour s'assurer que tous les composants n\u00e9cessaires - tels que les vis, les capuchons et les supports - sont inclus dans l'emballage et que le type et la quantit\u00e9 de composants correspondent \u00e0 la commande ou \u00e0 la documentation technique.\t\t\t<\/p>\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-09007b3 \" data-id=\"09007b3\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb7b11e elementor-widget elementor-widget-udesign_widget_flipbox\" data-id=\"eb7b11e\" data-element_type=\"widget\" data-widget_type=\"udesign_widget_flipbox.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<div id=\"flipbox-eb7b11e\" class=\"flipbox slide fb-slide-left\" data-flipbox-settings=\"{\r\n\t'effect': fb-slide-left}\">\r\n\t<!-- Front Side Content -->\r\n\t<div id=\"flipbox_front-eb7b11e\" class=\"flipbox_front center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\t\t\t<h3 class=\"flipbox-title\">\r\n\t\t\t\tOutils de soutien avanc\u00e9s\t\t\t<\/h3>\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<!-- Back Side Content -->\r\n\t<div id=\"flipbox_back-eb7b11e\" class=\"flipbox_back center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\t\t\t<p class=\"flipbox-description\">\r\n\t\t\t\tDes compteurs automatiques et des lignes de production sont utilis\u00e9s pour minimiser les erreurs humaines et garantir une qualit\u00e9 d'assemblage constante.\t\t\t<\/p>\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1dd8cbf \" data-id=\"1dd8cbf\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67506b2 elementor-widget elementor-widget-udesign_widget_flipbox\" data-id=\"67506b2\" data-element_type=\"widget\" data-widget_type=\"udesign_widget_flipbox.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<div id=\"flipbox-67506b2\" class=\"flipbox slide fb-slide-left\" data-flipbox-settings=\"{\r\n\t'effect': fb-slide-left}\">\r\n\t<!-- Front Side Content -->\r\n\t<div id=\"flipbox_front-67506b2\" class=\"flipbox_front center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\t\t\t<h3 class=\"flipbox-title\">\r\n\t\t\t\tSuivi de la productivit\u00e9 num\u00e9rique\t\t\t<\/h3>\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<!-- Back Side Content -->\r\n\t<div id=\"flipbox_back-67506b2\" class=\"flipbox_back center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\t\t\t<p class=\"flipbox-description\">\r\n\t\t\t\tLes temps de cycle sont suivis num\u00e9riquement en temps r\u00e9el, ce qui permet une visibilit\u00e9 imm\u00e9diate des performances et de l'efficacit\u00e9 de la production.\t\t\t<\/p>\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-94c1820 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"94c1820\" data-element_type=\"section\" id=\"FQC\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;arrow&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\r\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b2a23c \" data-id=\"8b2a23c\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-5eb154b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5eb154b\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-75dca15 \" data-id=\"75dca15\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89678f4 elementor-widget elementor-widget-heading\" data-id=\"89678f4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">03 Contr\u00f4le final de la qualit\u00e9<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f309d01 elementor-widget elementor-widget-text-editor\" data-id=\"f309d01\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"\" data-start=\"73\" data-end=\"556\">L&#8217;inspection finale permet de s&#8217;assurer que chaque produit r\u00e9pond aux normes requises avant d&#8217;\u00eatre exp\u00e9di\u00e9. Tous les r\u00e9sultats sont enregistr\u00e9s dans des protocoles normalis\u00e9s de contr\u00f4le de la qualit\u00e9. <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-59d7c96 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59d7c96\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce04847 \" data-id=\"ce04847\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dc45d5 elementor-widget elementor-widget-heading\" data-id=\"3dc45d5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les aspects suivants sont v\u00e9rifi\u00e9s :<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-155c10ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"155c10ad\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6f8b0a90 \" data-id=\"6f8b0a90\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fb8aa94 elementor-widget elementor-widget-udesign_widget_flipbox\" data-id=\"4fb8aa94\" data-element_type=\"widget\" data-widget_type=\"udesign_widget_flipbox.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<div id=\"flipbox-4fb8aa94\" class=\"flipbox slide fb-slide-left\" data-flipbox-settings=\"{\r\n\t'effect': fb-slide-left}\">\r\n\t<!-- Front Side Content -->\r\n\t<div id=\"flipbox_front-4fb8aa94\" class=\"flipbox_front center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\t\t\t<h3 class=\"flipbox-title\">\r\n\t\t\t\tDimensions\t\t\t<\/h3>\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<!-- Back Side Content -->\r\n\t<div id=\"flipbox_back-4fb8aa94\" class=\"flipbox_back center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\t\t\t<p class=\"flipbox-description\">\r\n\t\t\t\tMesur\u00e9 \u00e0 l'aide d'un pied \u00e0 coulisse et d'une balance\t\t\t<\/p>\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-45221103 \" data-id=\"45221103\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4564c076 elementor-widget elementor-widget-udesign_widget_flipbox\" data-id=\"4564c076\" data-element_type=\"widget\" data-widget_type=\"udesign_widget_flipbox.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<div id=\"flipbox-4564c076\" class=\"flipbox slide fb-slide-left\" data-flipbox-settings=\"{\r\n\t'effect': fb-slide-left}\">\r\n\t<!-- Front Side Content -->\r\n\t<div id=\"flipbox_front-4564c076\" class=\"flipbox_front center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\t\t\t<h3 class=\"flipbox-title\">\r\n\t\t\t\tQualit\u00e9 de la surface\t\t\t<\/h3>\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<!-- Back Side Content -->\r\n\t<div id=\"flipbox_back-4564c076\" class=\"flipbox_back center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\t\t\t<p class=\"flipbox-description\">\r\n\t\t\t\tInspection visuelle et analyse au spectrophotom\u00e8tre pour d\u00e9tecter les fissures, les incoh\u00e9rences de couleur ou les d\u00e9fauts.\t\t\t<\/p>\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-166b72e8 \" data-id=\"166b72e8\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f3f01f2 elementor-widget elementor-widget-udesign_widget_flipbox\" data-id=\"3f3f01f2\" data-element_type=\"widget\" data-widget_type=\"udesign_widget_flipbox.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<div id=\"flipbox-3f3f01f2\" class=\"flipbox slide fb-slide-left\" data-flipbox-settings=\"{\r\n\t'effect': fb-slide-left}\">\r\n\t<!-- Front Side Content -->\r\n\t<div id=\"flipbox_front-3f3f01f2\" class=\"flipbox_front center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\t\t\t<h3 class=\"flipbox-title\">\r\n\t\t\t\tFonctionnalit\u00e9\t\t\t<\/h3>\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<!-- Back Side Content -->\r\n\t<div id=\"flipbox_back-3f3f01f2\" class=\"flipbox_back center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\t\t\t<p class=\"flipbox-description\">\r\n\t\t\t\tEssais fonctionnels pour v\u00e9rifier la performance du produit\t\t\t<\/p>\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f8a3b83 \" data-id=\"f8a3b83\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c64e751 elementor-widget elementor-widget-udesign_widget_flipbox\" data-id=\"c64e751\" data-element_type=\"widget\" data-widget_type=\"udesign_widget_flipbox.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<div id=\"flipbox-c64e751\" class=\"flipbox slide fb-slide-left\" data-flipbox-settings=\"{\r\n\t'effect': fb-slide-left}\">\r\n\t<!-- Front Side Content -->\r\n\t<div id=\"flipbox_front-c64e751\" class=\"flipbox_front center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\t\t\t<h3 class=\"flipbox-title\">\r\n\t\t\t\tContr\u00f4le du poids\t\t\t<\/h3>\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t<!-- Back Side Content -->\r\n\t<div id=\"flipbox_back-c64e751\" class=\"flipbox_back center-align\">\r\n\t\t\r\n\t\t<div class=\"flipbox-content\">\r\n\t\t\t<!-- Title -->\r\n\t\t\t\r\n\t\t\t<!-- Subtitle -->\r\n\t\t\t\r\n\t\t\t<!-- Description -->\r\n\t\t\t\t\t\t<p class=\"flipbox-description\">\r\n\t\t\t\tPour garantir la quantit\u00e9 et la pr\u00e9cision\t\t\t<\/p>\r\n\t\t\t\r\n\t\t\t<!-- View more button -->\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-18efe93 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"18efe93\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f7bbbb \" data-id=\"3f7bbbb\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc71b94 elementor-widget elementor-widget-image\" data-id=\"cc71b94\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/05\/Plasterboard_installation_profiles_assembly_items_gkp_profiles_solar_components_sustainability_screws_bolts_fasteners_-JOLDIJAGROUP_j1-1024x683.jpg\" class=\"attachment-large size-large wp-image-20203\" alt=\"\" srcset=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/05\/Plasterboard_installation_profiles_assembly_items_gkp_profiles_solar_components_sustainability_screws_bolts_fasteners_-JOLDIJAGROUP_j1-1024x683.jpg 1024w, https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/05\/Plasterboard_installation_profiles_assembly_items_gkp_profiles_solar_components_sustainability_screws_bolts_fasteners_-JOLDIJAGROUP_j1-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-1c9ffcc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c9ffcc\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c5e78e \" data-id=\"6c5e78e\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2a3732 elementor-widget elementor-widget-heading\" data-id=\"e2a3732\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qualit\u00e9 certifi\u00e9e. Performance prouv\u00e9e. <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-7c721ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c721ce\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3471c96 \" data-id=\"3471c96\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fc1956 elementor-widget elementor-widget-text-editor\" data-id=\"3fc1956\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"\" data-start=\"198\" data-end=\"355\">Pour garantir une fiabilit\u00e9 durable, nos produits sont test\u00e9s en termes de durabilit\u00e9 m\u00e9canique, de r\u00e9sistance \u00e0 la charge, de protection contre la corrosion et de s\u00e9curit\u00e9 chimique.<\/p>\n<p class=\"\" data-start=\"357\" data-end=\"685\">Les tests sont effectu\u00e9s dans des laboratoires accr\u00e9dit\u00e9s et en interne, conform\u00e9ment aux normes EN et ISO strictes, notamment :<br data-start=\"484\" data-end=\"487\">&#8211; Essai de r\u00e9sistance \u00e0 la corrosion au brouillard salin (ISO 9227)<br data-start=\"544\" data-end=\"547\">&#8211; Essais de durabilit\u00e9 et de charge pour les charni\u00e8res et les glissi\u00e8res de tiroirs (EN 15570, EN 15338)<br data-start=\"629\" data-end=\"632\">&#8211; Analyse chimique pour la conformit\u00e9 REACH et RoHS<\/p>\n<p class=\"\" data-start=\"687\" data-end=\"843\">Nous effectuons \u00e9galement des tests internes de cycle et de corrosion pour garantir la qualit\u00e9 de tous les lots de production. Les r\u00e9sultats des tests sont document\u00e9s et suivis dans le temps. <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b2cb6c elementor-widget elementor-widget-heading\" data-id=\"2b2cb6c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conformit\u00e9<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c35615b elementor-widget elementor-widget-text-editor\" data-id=\"c35615b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous sommes fiers de collaborer avec des entreprises du monde entier sur un portefeuille diversifi\u00e9 de projets. Nous exportons principalement nos produits vers les march\u00e9s suivants. <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-55fe462f elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"55fe462f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-53974544 \" data-id=\"53974544\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25d433ac elementor-invisible elementor-widget elementor-widget-image\" data-id=\"25d433ac\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"631\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/2024\/12\/Dizainas-be-pavadinimo-2024-12-17T104709.450-e1734425276261-1024x631.png\" class=\"attachment-large size-large wp-image-13413\" alt=\"\" srcset=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/2024\/12\/Dizainas-be-pavadinimo-2024-12-17T104709.450-e1734425276261-1024x631.png 1024w, https:\/\/joldijagroup.com\/wp-content\/uploads\/2024\/12\/Dizainas-be-pavadinimo-2024-12-17T104709.450-e1734425276261-768x474.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5447ea2e \" data-id=\"5447ea2e\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a14b86f elementor-widget elementor-widget-heading\" data-id=\"1a14b86f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gestion de la qualit\u00e9 certifi\u00e9e ISO 9001<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-390c266f elementor-widget elementor-widget-text-editor\" data-id=\"390c266f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"\" data-start=\"164\" data-end=\"353\">Nous sommes certifi\u00e9s ISO 9001 depuis 2021 &#8211; une norme mondialement reconnue qui garantit que nos produits et nos processus r\u00e9pondent constamment aux attentes des clients et aux exigences r\u00e9glementaires.<\/p>\n<p class=\"\" data-start=\"355\" data-end=\"644\">Cette certification refl\u00e8te notre engagement en faveur de la qualit\u00e9 \u00e0 chaque \u00e9tape : des processus clairement document\u00e9s \u00e0 la tra\u00e7abilit\u00e9 compl\u00e8te, en passant par l&#8217;\u00e9valuation des risques, les audits internes et l&#8217;am\u00e9lioration continue. Nous suivons activement les performances, traitons les non-conformit\u00e9s et investissons dans la formation continue de nos employ\u00e9s. <\/p>\n<p class=\"\" data-start=\"646\" data-end=\"727\">Pour nous, ISO 9001 est plus qu&#8217;un certificat &#8211; c&#8217;est le fondement de notre fa\u00e7on de travailler.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-2032d753 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"2032d753\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5f7476a \" data-id=\"5f7476a\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-282c0d93 elementor-widget elementor-widget-heading\" data-id=\"282c0d93\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Durabilit\u00e9 certifi\u00e9e FSC<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f84ecd5 elementor-widget elementor-widget-text-editor\" data-id=\"5f84ecd5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"\" data-start=\"172\" data-end=\"292\">Nous sommes certifi\u00e9s FSC\u00ae depuis 2022 &#8211; une marque de gestion foresti\u00e8re responsable et d&#8217;approvisionnement respectueux de l&#8217;environnement.<\/p>\n<p class=\"\" data-start=\"294\" data-end=\"542\">Cette certification garantit que le bois et les mat\u00e9riaux forestiers que nous utilisons proviennent de for\u00eats g\u00e9r\u00e9es de mani\u00e8re responsable ou de sources recycl\u00e9es v\u00e9rifi\u00e9es. Nos produits respectent les normes d&#8217;\u00e9tiquetage du FSC, ce qui favorise le d\u00e9veloppement durable et s&#8217;aligne sur les objectifs ESG mondiaux. <\/p>\n<p class=\"\" data-start=\"544\" data-end=\"626\">Pour nous, FSC\u00ae signifie plus que la conformit\u00e9 &#8211; c&#8217;est notre engagement pour un avenir plus vert.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b18320 elementor-widget elementor-widget-text-editor\" data-id=\"5b18320\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p data-start=\"544\" data-end=\"626\"><a href=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/06\/JOLDIJA-UAB-FSC-COC-Certificate-30.5.2025.pdf\">T\u00e9l\u00e9chargez le certificat FSC (PDF)<\/a><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-335410a \" data-id=\"335410a\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31233fe2 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"31233fe2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"529\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/2024\/12\/Dizainas-be-pavadinimo-2024-12-16T085116.349-e1734424798957-1024x529.png\" class=\"attachment-large size-large wp-image-13408\" alt=\"FSC\" srcset=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/2024\/12\/Dizainas-be-pavadinimo-2024-12-16T085116.349-e1734424798957-1024x529.png 1024w, https:\/\/joldijagroup.com\/wp-content\/uploads\/2024\/12\/Dizainas-be-pavadinimo-2024-12-16T085116.349-e1734424798957-768x397.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-28837e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28837e3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-95b64dd \" data-id=\"95b64dd\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a39c063 elementor-widget elementor-widget-heading\" data-id=\"a39c063\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sant\u00e9 et s\u00e9curit\u00e9<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-467086e elementor-widget elementor-widget-text-editor\" data-id=\"467086e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"flex max-w-full flex-col flex-grow\">\n<div class=\"min-h-8 text-message flex w-full flex-col items-end gap-2 whitespace-normal break-words text-start [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"114c0822-8059-4445-8c16-14600bc9b679\" data-message-model-slug=\"gpt-4o-mini\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p class=\"\" data-start=\"118\" data-end=\"434\">La sant\u00e9 et la s\u00e9curit\u00e9 sont nos principales priorit\u00e9s. Nous nous engageons \u00e0 maintenir un environnement de travail s\u00fbr en respectant strictement les r\u00e9glementations en mati\u00e8re de sant\u00e9 et de s\u00e9curit\u00e9. Gr\u00e2ce \u00e0 des formations r\u00e9guli\u00e8res, \u00e0 des \u00e9valuations approfondies des risques et \u00e0 des mesures de s\u00e9curit\u00e9 efficaces, nous veillons \u00e0 ce que nos lieux de travail soient exempts de dangers et favorisent le bien-\u00eatre de notre \u00e9quipe.  <\/p>\n<p class=\"\" data-start=\"436\" data-end=\"579\">Notre engagement va au-del\u00e0 de la conformit\u00e9 &#8211; il refl\u00e8te notre responsabilit\u00e9 \u00e0 l&#8217;\u00e9gard de nos employ\u00e9s et notre culture de la s\u00e9curit\u00e9 et de l&#8217;attention dans tout ce que nous faisons.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7e4d913 \" data-id=\"7e4d913\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-877df97 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"877df97\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/02\/safety-1024x1024.jpg\" class=\"attachment-large size-large wp-image-14926\" alt=\"\" srcset=\"https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/02\/safety-1024x1024.jpg 1024w, https:\/\/joldijagroup.com\/wp-content\/uploads\/2025\/02\/safety-768x768.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-321490d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"321490d\" data-element_type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b895353 \" data-id=\"b895353\" data-element_type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Qualit\u00e9 Notre engagement en faveur de la qualit\u00e9 garantit des solutions durables, fiables et bien con\u00e7ues. Contr\u00f4le de la qualit\u00e9 : Du concept \u00e0 l&#8217;am\u00e9lioration continue Le contr\u00f4le de la qualit\u00e9 au sein du groupe Joldija est un processus complet, en plusieurs \u00e9tapes, int\u00e9gr\u00e9 \u00e0 chaque phase du d\u00e9veloppement et de la fabrication des produits. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-22744","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/pages\/22744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/comments?post=22744"}],"version-history":[{"count":1,"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/pages\/22744\/revisions"}],"predecessor-version":[{"id":22757,"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/pages\/22744\/revisions\/22757"}],"wp:attachment":[{"href":"https:\/\/joldijagroup.com\/fr\/wp-json\/wp\/v2\/media?parent=22744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}